{"id":43,"date":"2023-11-10T18:25:30","date_gmt":"2023-11-10T18:25:30","guid":{"rendered":"https:\/\/350hope.com\/?page_id=43"},"modified":"2026-02-27T19:15:46","modified_gmt":"2026-02-27T19:15:46","slug":"practice","status":"publish","type":"page","link":"https:\/\/350hope.com\/es\/practice\/","title":{"rendered":"PR\u00c1CTICA"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"43\" class=\"elementor elementor-43\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37987b57 e-con-full e-flex e-con e-parent\" data-id=\"37987b57\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5df44f5b e-con-full e-flex e-con e-child\" data-id=\"5df44f5b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b5e6c41 elementor-widget elementor-widget-image\" data-id=\"7b5e6c41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/350hope.com\/es\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-1024x601.png\" class=\"attachment-large size-large wp-image-57\" alt=\"\" srcset=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-1024x601.png 1024w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-300x176.png 300w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-768x451.png 768w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22c35203 e-con-full e-flex e-con e-child\" data-id=\"22c35203\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ed8574c elementor-nav-menu__align-center elementor-nav-menu--stretch elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"5ed8574c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fa\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-text e--animation-grow\">\n\t\t\t\t<ul id=\"menu-1-5ed8574c\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-54\"><a href=\"https:\/\/350hope.com\/es\/practice\/\" class=\"elementor-item\">PR\u00c1CTICA<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-527\"><a href=\"https:\/\/350hope.com\/es\/family-law\/\" class=\"elementor-sub-item\">LEY FAMILIAR<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-525\"><a href=\"https:\/\/350hope.com\/es\/will-estate-planning\/\" class=\"elementor-sub-item\">TESTAMENTOS Y PLANIFICACI\u00d3N PATRIMONIAL<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-528\"><a href=\"https:\/\/350hope.com\/es\/probate\/\" class=\"elementor-sub-item\">LEGALIZACI\u00d3N DE UN TESTAMENTO<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-529\"><a href=\"https:\/\/350hope.com\/es\/dwi-law\/\" class=\"elementor-sub-item\">DWI<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-53\"><a href=\"https:\/\/350hope.com\/es\/about\/\" class=\"elementor-item\">NUESTRO EQUIPO<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-52\"><a href=\"https:\/\/350hope.com\/es\/blog\/\" class=\"elementor-item\">BLOG<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-51\"><a href=\"https:\/\/350hope.com\/es\/contact\/\" class=\"elementor-item\">CONTACTO<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Alternar men\u00fa\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-5ed8574c\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-54\"><a href=\"https:\/\/350hope.com\/es\/practice\/\" class=\"elementor-item\" tabindex=\"-1\">PR\u00c1CTICA<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-527\"><a href=\"https:\/\/350hope.com\/es\/family-law\/\" class=\"elementor-sub-item\" tabindex=\"-1\">LEY FAMILIAR<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-525\"><a href=\"https:\/\/350hope.com\/es\/will-estate-planning\/\" class=\"elementor-sub-item\" tabindex=\"-1\">TESTAMENTOS Y PLANIFICACI\u00d3N PATRIMONIAL<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-528\"><a href=\"https:\/\/350hope.com\/es\/probate\/\" class=\"elementor-sub-item\" tabindex=\"-1\">LEGALIZACI\u00d3N DE UN TESTAMENTO<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-529\"><a href=\"https:\/\/350hope.com\/es\/dwi-law\/\" class=\"elementor-sub-item\" tabindex=\"-1\">DWI<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-53\"><a href=\"https:\/\/350hope.com\/es\/about\/\" class=\"elementor-item\" tabindex=\"-1\">NUESTRO EQUIPO<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-52\"><a href=\"https:\/\/350hope.com\/es\/blog\/\" class=\"elementor-item\" tabindex=\"-1\">BLOG<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-51\"><a href=\"https:\/\/350hope.com\/es\/contact\/\" class=\"elementor-item\" tabindex=\"-1\">CONTACTO<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c16502f e-con-full e-flex e-con e-child\" data-id=\"7c16502f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6255e05b elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6255e05b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:%20806-3504673\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(806) 350-4673<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-104191e5 e-con-full e-flex e-con e-child\" data-id=\"104191e5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e85fcf2 elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e85fcf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/350hope.com\/es\/contact\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cont\u00e1ctenos<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-710fc54c e-flex e-con-boxed e-con e-parent\" data-id=\"710fc54c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;pyramids&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M761.9,44.1L643.1,27.2L333.8,98L0,3.8V0l1000,0v3.9\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74102d57 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"74102d57\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AREAS DE PR\u00c1CTICA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1630832c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1630832c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInDown&quot;,&quot;_animation_delay&quot;:0.75}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AYUDANDO A LAS PERSONAS CON SUS PROBLEMAS LEGALES DESDE 1998<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff18034 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"ff18034\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-pp-wrapper-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/350hope.com\\\/family-law\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" class=\"pp-wrapper-link elementor-element elementor-element-c9cc95c e-con-full e-flex e-con e-child\" data-id=\"c9cc95c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4ffdf4 elementor-widget elementor-widget-image\" data-id=\"b4ffdf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"772\" src=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/gavel-1-1024x988.png\" class=\"attachment-large size-large wp-image-507\" alt=\"\" srcset=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/gavel-1-1024x988.png 1024w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/gavel-1-300x289.png 300w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/gavel-1-768x741.png 768w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/gavel-1.png 1300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57d3a65 elementor-widget elementor-widget-heading\" data-id=\"57d3a65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LEY FAMILIAR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-513bab6 elementor-widget elementor-widget-text-editor\" data-id=\"513bab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lidiar con un asunto legal que involucra a su familia puede ser una de las experiencias m\u00e1s dif\u00edciles y emocionales de su vida. Necesita un abogado experimentado en quien pueda confiar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65755ec elementor-widget elementor-widget-button\" data-id=\"65755ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/350hope.com\/es\/family-law\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">M\u00c1S INFORMACI\u00d3N<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-pp-wrapper-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/350hope.com\\\/will-trust-law\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" class=\"pp-wrapper-link elementor-element elementor-element-3eb18d6 e-con-full e-flex e-con e-child\" data-id=\"3eb18d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36a8213 elementor-widget elementor-widget-image\" data-id=\"36a8213\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/350hope.com\/es\/will-estate-planning\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"772\" src=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/will-1024x988.jpg\" class=\"attachment-large size-large wp-image-511\" alt=\"\" srcset=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/will-1024x988.jpg 1024w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/will-300x289.jpg 300w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/will-768x741.jpg 768w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/will.jpg 1300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0df9020 elementor-widget elementor-widget-heading\" data-id=\"0df9020\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TESTAMENTOS Y PLANIFICACI\u00d3N PATRIMONIAL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9183595 elementor-widget elementor-widget-text-editor\" data-id=\"9183595\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Decidir qu\u00e9 pasar\u00e1 con su hogar, sus activos financieros y sus posesiones personales despu\u00e9s de su fallecimiento puede ser un proceso dif\u00edcil y en el que pensar mucho.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8147623 elementor-widget elementor-widget-button\" data-id=\"8147623\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/350hope.com\/es\/will-estate-planning\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">M\u00c1S INFORMACI\u00d3N<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-229e91c e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"229e91c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div data-pp-wrapper-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/350hope.com\\\/estate-planning\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" class=\"pp-wrapper-link elementor-element elementor-element-c6a1139 e-con-full e-flex e-con e-child\" data-id=\"c6a1139\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34af5ae elementor-widget elementor-widget-image\" data-id=\"34af5ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/350hope.com\/es\/probate\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"772\" src=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/house-1-1024x988.png\" class=\"attachment-large size-large wp-image-510\" alt=\"\" srcset=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/house-1-1024x988.png 1024w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/house-1-300x289.png 300w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/house-1-768x741.png 768w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/house-1.png 1300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6148372 elementor-widget elementor-widget-heading\" data-id=\"6148372\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LEGALIZACI\u00d3N DE UN TESTAMENTO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e40a4d6 elementor-widget elementor-widget-text-editor\" data-id=\"e40a4d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>Con un profundo conocimiento de las leyes patrimoniales y un compromiso con el servicio personalizado, nos aseguramos de que sus activos se administren y distribuyan eficazmente de acuerdo con sus deseos. Ya sea que est\u00e9 considerando redactar un testamento, establecer fideicomisos o navegar por las complejidades del tribunal testamentario, ll\u00e1menos, podemos ayudarlo.<\/div><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ae7cb3 elementor-widget elementor-widget-button\" data-id=\"1ae7cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/350hope.com\/es\/probate\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">M\u00c1S INFORMACI\u00d3N<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-pp-wrapper-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/350hope.com\\\/dwi-law\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" class=\"pp-wrapper-link elementor-element elementor-element-dd2b6b0 e-con-full e-flex e-con e-child\" data-id=\"dd2b6b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78db598 elementor-widget elementor-widget-image\" data-id=\"78db598\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"360\" src=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/DWI-LAW-1.jpeg\" class=\"attachment-large size-large wp-image-509\" alt=\"\" srcset=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/DWI-LAW-1.jpeg 360w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/DWI-LAW-1-300x300.jpeg 300w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/DWI-LAW-1-150x150.jpeg 150w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b93a4e3 elementor-widget elementor-widget-heading\" data-id=\"b93a4e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LEY DE DWI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12c2cba elementor-widget elementor-widget-text-editor\" data-id=\"12c2cba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si le han acusado de DWI en Texas, su primer paso deber\u00eda ser una llamada telef\u00f3nica. Discutiremos sus cargos y daremos el siguiente paso juntos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d2ac24 elementor-widget elementor-widget-button\" data-id=\"8d2ac24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/350hope.com\/es\/dwi-law\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">M\u00c1S INFORMACI\u00d3N<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6dec933a e-flex e-con-boxed e-con e-parent\" data-id=\"6dec933a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;triangle-asymmetrical&quot;,&quot;shape_divider_top_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M737.9,94.7L0,0v100h1000V0L737.9,94.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73c60aa5 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"73c60aa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">COMUN\u00cdQUESE CON NOSOTROS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14e1a52 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"14e1a52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg elementor-animation-pulse-grow\" href=\"https:\/\/350hope.com\/es\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ponerse en contacto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6146a6fd e-con-full e-flex e-con e-parent\" data-id=\"6146a6fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-102841be e-con-full e-flex e-con e-parent\" data-id=\"102841be\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fd71c9d e-con-full e-flex e-con e-child\" data-id=\"fd71c9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cbd8063 elementor-widget elementor-widget-image\" data-id=\"5cbd8063\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"470\" src=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-1-1024x601.png\" class=\"attachment-large size-large wp-image-162\" alt=\"\" srcset=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-1-1024x601.png 1024w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-1-300x176.png 300w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-1-768x451.png 768w, https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-1.png 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac349c0 elementor-widget elementor-widget-heading\" data-id=\"2ac349c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Direcci\u00f3n: Eagle Center, 112 SW 8th Ave<br> Suite 400, Amarillo, TX 79101<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68908324 pp-icon-list-traditional elementor-list-item-link-inline pp-icon-left elementor-widget elementor-widget-pp-icon-list\" data-id=\"68908324\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-list-container\">\n\t\t\t<ul class=\"pp-list-items\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"pp-icon-list-item elementor-repeater-item-e2a7b3b\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:%20806-3504673\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon-list-icon pp-icon\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg><\/span>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon-list-text\">\n\t\t\t\t\t\t\t\t(806) 350-4673\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"pp-icon-list-item elementor-repeater-item-10f5afd\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/350hope.com\/es\/contact\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon-list-icon pp-icon\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-envelope\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464 64H48C21.49 64 0 85.49 0 112v288c0 26.51 21.49 48 48 48h416c26.51 0 48-21.49 48-48V112c0-26.51-21.49-48-48-48zm0 48v40.805c-22.422 18.259-58.168 46.651-134.587 106.49-16.841 13.247-50.201 45.072-73.413 44.701-23.208.375-56.579-31.459-73.413-44.701C106.18 199.465 70.425 171.067 48 152.805V112h416zM48 400V214.398c22.914 18.251 55.409 43.862 104.938 82.646 21.857 17.205 60.134 55.186 103.062 54.955 42.717.231 80.509-37.199 103.053-54.947 49.528-38.783 82.032-64.401 104.947-82.653V400H48z\"><\/path><\/svg><\/span>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon-list-text\">\n\t\t\t\t\t\t\t\tCont\u00e1ctenos\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b47087a e-grid-align-left e-grid-align-mobile-center elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"7b47087a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-8073928\" href=\"https:\/\/www.facebook.com\/abbottlaw\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-9d6b236\" href=\"https:\/\/www.youtube.com\/channel\/UCLLUXojCgIOETuA0wC6IAUA\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">YouTube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-9f85620\" href=\"http:\/\/www.instagram.com\/abbottlawoffice\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-4810625\" href=\"http:\/\/linkedin.com\/company\/abbott-law-amarillo\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">LinkedIn<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon- elementor-repeater-item-1bc5d05\" href=\"http:\/\/www.tiktok.com\/@abbottlaw\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\"><\/span>\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_2\" data-name=\"Layer 2\" viewbox=\"0 0 419 419\"><defs><style>      .cls-1 {        stroke-width: 0px;      }    <\/style><\/defs><g id=\"Layer_2-2\" data-name=\"Layer 2\"><path class=\"cls-1\" d=\"m394,0H25C11.19,0,0,11.19,0,25v369c0,13.81,11.19,25,25,25h369c13.81,0,25-11.19,25-25V25c0-13.81-11.19-25-25-25Zm-61.04,180.06c-24.28,0-46.78-7.77-65.14-20.94v95.14c0,47.51-38.65,86.17-86.17,86.17-18.36,0-35.39-5.79-49.38-15.62-22.23-15.6-36.79-41.4-36.79-70.55,0-47.52,38.66-86.17,86.17-86.17,3.94,0,7.8.32,11.61.84v47.79c-3.67-1.15-7.56-1.82-11.61-1.82-21.69,0-39.35,17.66-39.35,39.36,0,15.11,8.58,28.24,21.1,34.82,5.46,2.88,11.67,4.52,18.26,4.52,21.2,0,38.49-16.86,39.27-37.87l.08-187.62h46.81c0,4.06.4,8.03,1.11,11.88,3.3,17.83,13.89,33.14,28.55,42.7,10.22,6.66,22.4,10.55,35.47,10.55v46.82Z\"><\/path><\/g><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5692a234 e-con-full e-flex e-con e-child\" data-id=\"5692a234\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9bdcfc elementor-widget elementor-widget-pp-business-hours\" data-id=\"c9bdcfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-business-hours.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-business-hours\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-business-hours-row clearfix elementor-repeater-item-5657700\">\n\t\t\t\t<span class=\"pp-business-day\">\n\t\t\t\t\tLunes\t\t\t\t<\/span>\n\t\t\t\t<span class=\"pp-business-timing\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-opening-hours\">\n\t\t\t\t\t\t\t08:30 AM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t-\n\t\t\t\t\t\t<span class=\"pp-closing-hours\">\n\t\t\t\t\t\t\t5:00 PM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-business-hours-row clearfix elementor-repeater-item-ec2ab46\">\n\t\t\t\t<span class=\"pp-business-day\">\n\t\t\t\t\tMartes\t\t\t\t<\/span>\n\t\t\t\t<span class=\"pp-business-timing\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-opening-hours\">\n\t\t\t\t\t\t\t08:30 AM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t-\n\t\t\t\t\t\t<span class=\"pp-closing-hours\">\n\t\t\t\t\t\t\t5:00 PM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-business-hours-row clearfix elementor-repeater-item-93a6ae7\">\n\t\t\t\t<span class=\"pp-business-day\">\n\t\t\t\t\tMi\u00e9rcoles\t\t\t\t<\/span>\n\t\t\t\t<span class=\"pp-business-timing\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-opening-hours\">\n\t\t\t\t\t\t\t08:30 AM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t-\n\t\t\t\t\t\t<span class=\"pp-closing-hours\">\n\t\t\t\t\t\t\t5:00 PM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-business-hours-row clearfix elementor-repeater-item-b8a51d0\">\n\t\t\t\t<span class=\"pp-business-day\">\n\t\t\t\t\tJueves\t\t\t\t<\/span>\n\t\t\t\t<span class=\"pp-business-timing\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-opening-hours\">\n\t\t\t\t\t\t\t08:30 AM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t-\n\t\t\t\t\t\t<span class=\"pp-closing-hours\">\n\t\t\t\t\t\t\t5:00 PM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-business-hours-row clearfix elementor-repeater-item-ee96797\">\n\t\t\t\t<span class=\"pp-business-day\">\n\t\t\t\t\tViernes\t\t\t\t<\/span>\n\t\t\t\t<span class=\"pp-business-timing\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-opening-hours\">\n\t\t\t\t\t\t\t08:30 AM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t-\n\t\t\t\t\t\t<span class=\"pp-closing-hours\">\n\t\t\t\t\t\t\t12:00 PM\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-business-hours-row clearfix elementor-repeater-item-bcc93bd row-closed\">\n\t\t\t\t<span class=\"pp-business-day\">\n\t\t\t\t\tS\u00e1bado\t\t\t\t<\/span>\n\t\t\t\t<span class=\"pp-business-timing\">\n\t\t\t\t\tCon cita\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-business-hours-row clearfix elementor-repeater-item-0c4f770 row-closed\">\n\t\t\t\t<span class=\"pp-business-day\">\n\t\t\t\t\tDomingo\t\t\t\t<\/span>\n\t\t\t\t<span class=\"pp-business-timing\">\n\t\t\t\t\tCon cita\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72cac2b e-con-full e-flex e-con e-child\" data-id=\"72cac2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72874d52 elementor-widget elementor-widget-heading\" data-id=\"72874d52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NOTA ESPECIAL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ec67e3e elementor-widget elementor-widget-text-editor\" data-id=\"6ec67e3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Consulte a un abogado para obtener asesoramiento sobre su situaci\u00f3n individual. Este sitio y su informaci\u00f3n no son asesoramiento legal ni pretenden serlo. No dude en ponerse en contacto por correo electr\u00f3nico, cartas o llamadas telef\u00f3nicas. Contactarnos no crea una relaci\u00f3n abogado-cliente. Hasta que se establezca una relaci\u00f3n abogado-cliente, no nos env\u00ede informaci\u00f3n confidencial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>(806) 350-HOPE Contact Us PRACTICE AREAS HELPING PEOPLE WITH THEIR LEGAL PROBLEMS SINCE 1998 FAMILY LAW Dealing with a legal issue involving your family can be one of the most difficult and emotional experiences of your life. You need an experienced attorney you can trust. MORE INFO WILLS &amp; ESTATE PLANNING Deciding what\u2019ll happen to [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-43","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PRACTICE - 350hope<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/350hope.com\/es\/practice\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRACTICE - 350hope\" \/>\n<meta property=\"og:description\" content=\"(806) 350-HOPE Contact Us PRACTICE AREAS HELPING PEOPLE WITH THEIR LEGAL PROBLEMS SINCE 1998 FAMILY LAW Dealing with a legal issue involving your family can be one of the most difficult and emotional experiences of your life. You need an experienced attorney you can trust. MORE INFO WILLS &amp; ESTATE PLANNING Deciding what\u2019ll happen to [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/350hope.com\/es\/practice\/\" \/>\n<meta property=\"og:site_name\" content=\"350hope\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abbottlaw\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T19:15:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"881\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/350hope.com\\\/practice\\\/\",\"url\":\"https:\\\/\\\/350hope.com\\\/practice\\\/\",\"name\":\"PRACTICE - 350hope\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/350hope.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/350hope.com\\\/practice\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/350hope.com\\\/practice\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/350hope.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/abbott-white-1024x601.png\",\"datePublished\":\"2023-11-10T18:25:30+00:00\",\"dateModified\":\"2026-02-27T19:15:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/350hope.com\\\/practice\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/350hope.com\\\/practice\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/350hope.com\\\/practice\\\/#primaryimage\",\"url\":\"https:\\\/\\\/350hope.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/abbott-white-1024x601.png\",\"contentUrl\":\"https:\\\/\\\/350hope.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/abbott-white-1024x601.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/350hope.com\\\/practice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/350hope.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRACTICE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/350hope.com\\\/#website\",\"url\":\"https:\\\/\\\/350hope.com\\\/\",\"name\":\"350hope\",\"description\":\"There Is Hope\",\"publisher\":{\"@id\":\"https:\\\/\\\/350hope.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/350hope.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/350hope.com\\\/#organization\",\"name\":\"Abbott Law Office\",\"url\":\"https:\\\/\\\/350hope.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/350hope.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/350hope.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-Fav_350.png\",\"contentUrl\":\"https:\\\/\\\/350hope.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-Fav_350.png\",\"width\":300,\"height\":251,\"caption\":\"Abbott Law Office\"},\"image\":{\"@id\":\"https:\\\/\\\/350hope.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/abbottlaw\\\/\",\"http:\\\/\\\/www.instagram.com\\\/abbottlawoffice\\\/\",\"http:\\\/\\\/www.tiktok.com\\\/@abbottlaw\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCLLUXojCgIOETuA0wC6IAUA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PRACTICE - 350hope","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/350hope.com\/es\/practice\/","og_locale":"es_MX","og_type":"article","og_title":"PRACTICE - 350hope","og_description":"(806) 350-HOPE Contact Us PRACTICE AREAS HELPING PEOPLE WITH THEIR LEGAL PROBLEMS SINCE 1998 FAMILY LAW Dealing with a legal issue involving your family can be one of the most difficult and emotional experiences of your life. You need an experienced attorney you can trust. MORE INFO WILLS &amp; ESTATE PLANNING Deciding what\u2019ll happen to [&hellip;]","og_url":"https:\/\/350hope.com\/es\/practice\/","og_site_name":"350hope","article_publisher":"https:\/\/www.facebook.com\/abbottlaw\/","article_modified_time":"2026-02-27T19:15:46+00:00","og_image":[{"width":1500,"height":881,"url":"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/350hope.com\/practice\/","url":"https:\/\/350hope.com\/practice\/","name":"PRACTICE - 350hope","isPartOf":{"@id":"https:\/\/350hope.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/350hope.com\/practice\/#primaryimage"},"image":{"@id":"https:\/\/350hope.com\/practice\/#primaryimage"},"thumbnailUrl":"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-1024x601.png","datePublished":"2023-11-10T18:25:30+00:00","dateModified":"2026-02-27T19:15:46+00:00","breadcrumb":{"@id":"https:\/\/350hope.com\/practice\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/350hope.com\/practice\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/350hope.com\/practice\/#primaryimage","url":"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-1024x601.png","contentUrl":"https:\/\/350hope.com\/wp-content\/uploads\/2023\/11\/abbott-white-1024x601.png"},{"@type":"BreadcrumbList","@id":"https:\/\/350hope.com\/practice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/350hope.com\/"},{"@type":"ListItem","position":2,"name":"PRACTICE"}]},{"@type":"WebSite","@id":"https:\/\/350hope.com\/#website","url":"https:\/\/350hope.com\/","name":"350esperanza","description":"There Is Hope","publisher":{"@id":"https:\/\/350hope.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/350hope.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/350hope.com\/#organization","name":"Abbott Law Office","url":"https:\/\/350hope.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/350hope.com\/#\/schema\/logo\/image\/","url":"https:\/\/350hope.com\/wp-content\/uploads\/2024\/01\/cropped-Fav_350.png","contentUrl":"https:\/\/350hope.com\/wp-content\/uploads\/2024\/01\/cropped-Fav_350.png","width":300,"height":251,"caption":"Abbott Law Office"},"image":{"@id":"https:\/\/350hope.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/abbottlaw\/","http:\/\/www.instagram.com\/abbottlawoffice\/","http:\/\/www.tiktok.com\/@abbottlaw","https:\/\/www.youtube.com\/channel\/UCLLUXojCgIOETuA0wC6IAUA"]}]}},"_links":{"self":[{"href":"https:\/\/350hope.com\/es\/wp-json\/wp\/v2\/pages\/43","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/350hope.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/350hope.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/350hope.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/350hope.com\/es\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":145,"href":"https:\/\/350hope.com\/es\/wp-json\/wp\/v2\/pages\/43\/revisions"}],"predecessor-version":[{"id":2508,"href":"https:\/\/350hope.com\/es\/wp-json\/wp\/v2\/pages\/43\/revisions\/2508"}],"wp:attachment":[{"href":"https:\/\/350hope.com\/es\/wp-json\/wp\/v2\/media?parent=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}